{"id":3462,"date":"2017-11-25T18:41:08","date_gmt":"2017-11-25T17:41:08","guid":{"rendered":"https:\/\/veesbook.net\/wordpress\/?page_id=3462"},"modified":"2019-07-09T07:39:21","modified_gmt":"2019-07-09T05:39:21","slug":"hofchronik-westervesede-nr-21-tieten","status":"publish","type":"page","link":"https:\/\/veesbook.net\/wordpress\/haus-und-hof\/haus-und-hof-1\/hofchronik-westervesede-nr-21-tieten\/","title":{"rendered":"Hofchronik Westervesede Nr. 21 &#8211; Schnittgers \/ Tieten"},"content":{"rendered":"<div class=\"one-half first\">\n<p>[ahmetiwptimeline groupid=&#8220;33&#8243; sort=&#8220;ASC&#8220; state=&#8220;close&#8220;]<\/p>\n<\/div><div class=\"one-half\">\n<figure id=\"attachment_4591\" aria-describedby=\"caption-attachment-4591\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"zoooom wp-image-4591 size-medium\" title=\"Historisches Bild der Hofstelle\" src=\"https:\/\/veesbook.net\/wordpress\/wp-content\/uploads\/2019\/07\/Westervesede-21-Tieten-300x215.jpg\" alt=\"Historisches Bild der Hofstelle\" width=\"300\" height=\"215\" srcset=\"https:\/\/veesbook.net\/wordpress\/wp-content\/uploads\/2019\/07\/Westervesede-21-Tieten-300x215.jpg 300w, https:\/\/veesbook.net\/wordpress\/wp-content\/uploads\/2019\/07\/Westervesede-21-Tieten-621x445.jpg 621w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-4591\" class=\"wp-caption-text\">Historisches Bild der Hofstelle<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3470\" aria-describedby=\"caption-attachment-3470\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3470\" src=\"https:\/\/veesbook.net\/wordpress\/wp-content\/uploads\/2017\/11\/Tieten-Hus-300x225.jpg\" alt=\"Wv Tieten-Hus\" width=\"300\" height=\"225\" srcset=\"https:\/\/veesbook.net\/wordpress\/wp-content\/uploads\/2017\/11\/Tieten-Hus-300x225.jpg 300w, https:\/\/veesbook.net\/wordpress\/wp-content\/uploads\/2017\/11\/Tieten-Hus-593x445.jpg 593w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-3470\" class=\"wp-caption-text\">Wv Tieten-Hus (2015)<\/figcaption><\/figure>\n<p>Das Wohnhaus ist eines der 5 <a href=\"https:\/\/veesbook.net\/wordpress\/historisches\/baudenkmale\/\">Baudenkmale<\/a> in Westervesede-<\/p>\n<p>&nbsp;<\/p>\n<p>1862 siedelte Johann Joachim Wulf an den \u00f6stlichen Ortsrand \u00a0(Osterbruch) aus. Er nahm den Hofnamen \u201eSchnittgers\u201c mit; die Hausnummer verblieb bei der alten Hofstelle, die den neuen Hofnahmen \u201eTieten\u201c erhielt.<\/p>\n<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":34,"featured_media":0,"parent":147,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":["post-3462","page","type-page","status-publish","entry"],"_links":{"self":[{"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/pages\/3462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/comments?post=3462"}],"version-history":[{"count":16,"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/pages\/3462\/revisions"}],"predecessor-version":[{"id":4595,"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/pages\/3462\/revisions\/4595"}],"up":[{"embeddable":true,"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/pages\/147"}],"wp:attachment":[{"href":"https:\/\/veesbook.net\/wordpress\/wp-json\/wp\/v2\/media?parent=3462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}